{"id":28803,"date":"2025-09-23T08:00:45","date_gmt":"2025-09-23T08:00:45","guid":{"rendered":"https:\/\/cogop.org\/?p=28803"},"modified":"2025-09-23T08:00:45","modified_gmt":"2025-09-23T08:00:45","slug":"discipulado-un-compromiso-hacia-nuestra-transformacion","status":"publish","type":"post","link":"https:\/\/cogop.org\/es\/discipulado-un-compromiso-hacia-nuestra-transformacion\/","title":{"rendered":"Discipulado: Un compromiso hacia nuestra transformaci\u00f3n"},"content":{"rendered":"<h2>Jes\u00fas conoce a Sus disc\u00edpulos | Parte 2<\/h2>\n<p>Nuestro objetivo en esta segunda parte se centrar\u00e1 en enfatizar el conocimiento que tiene Jes\u00fas de aquellos a quienes llama. Pero antes de proseguir, es importante recordar que el discipulado tal y como lo ejemplific\u00f3 Jes\u00fas no es un acontecimiento moment\u00e1neo, sino un compromiso de toda la vida. <\/p>\n<p>Seg\u00fan el Evangelio de Juan, Andr\u00e9s y otro disc\u00edpulo fueron los primeros en seguir a Jes\u00fas luego de escuchar a Juan el Bautista decir: \u201c\u00a1He aqu\u00ed el Cordero de Dios!\u201d (Juan 1:36). Juan el Bautista entendi\u00f3 que su misi\u00f3n era anunciar que Jes\u00fas era el Cordero de Dios y a \u00c9l se deb\u00eda seguir. La declaraci\u00f3n de Juan fue suficiente para que estos dos hombres decidieran dejarlo a \u00c9l y comenzaran a seguir a Jes\u00fas (Juan 1:37, 40).  <\/p>\n<p>Mientras Jes\u00fas caminaba, de repente vio que dos hombres lo segu\u00edan: <span class=\"Apple-converted-space\"> <\/span><\/p>\n<p>\u201cY volvi\u00e9ndose Jes\u00fas, y <b>viendo<\/b> que le <b>segu\u00edan<\/b>, les dijo: <b>\u00bfQu\u00e9 busc\u00e1is?<\/b> Ellos le dijeron: <b>Rab\u00ed <\/b>(que traducido es, Maestro), \u00bfd\u00f3nde moras? Les dijo: <b>Venid y ved.<\/b> Fueron, y vieron donde moraba, y <b>se quedaron<\/b> con \u00e9l aquel d\u00eda; porque era como la hora d\u00e9cima\u201d (Juan 1:38, 39).  <\/p>\n<p>Este pasaje contiene cinco verbos destacados y un t\u00edtulo que muestran la intencionalidad, la seriedad y el compromiso del discipulado transformador: <b>seguir, ver, buscar, Rab\u00ed, ven y ve, y quedar.<\/b><\/p>\n<p>El verbo <b>seguir<\/b>, <i>akoluthein<\/i>, est\u00e1 \u201cestrictamente limitado al discipulado de Cristo\u201d. En este acto de seguir, \u201cel disc\u00edpulo deja todo para seguir a Jes\u00fas (Marcos 10:28)\u201d. [Esta decisi\u00f3n de] seguir a Jes\u00fas implica que se rompen todos los dem\u00e1s lazos. De hecho, el v\u00ednculo con Jes\u00fas va por encima de los lazos familiares (Mateo 8:22; Lucas 9:61). \u201cEl uso exclusivo de <i>akoluthein<\/i> en el Nuevo Testamento estriba en el hecho de que para los creyentes primitivos hab\u00eda un solo discipulado y, por lo tanto, un solo seguimiento, esto es, la relaci\u00f3n con Jes\u00fas. La exigencia de Jes\u00fas cuando nos llama a seguirlo es una exigencia mesi\u00e1nica\u201d.1    <\/p>\n<p><i>Akoluthein<\/i> (seguir) significa participar en la salvaci\u00f3n que ofrece Jes\u00fas. Este seguir es una decisi\u00f3n de no mirar atr\u00e1s despu\u00e9s de poner la mano en el arado. El que mira hacia atr\u00e1s no es apto para el reino de los cielos (Lucas 9:61, 62). Este seguimiento tambi\u00e9n implica \u201cparticipar en el destino de Jes\u00fas\u201d. En Mateo 8:19, 20, Jes\u00fas respondi\u00f3 a aquel que dijo que lo seguir\u00eda: \u201c\u2014Las zorras tienen madrigueras y las aves tienen nidos\u2026 pero el Hijo del hombre no tiene d\u00f3nde recostar la cabeza\u201d (NVI). Participar en el destino de Jes\u00fas significa negarse a uno mismo, tomar la cruz y seguirlo (Marcos 8:34). Seguir a Jes\u00fas es \u201cuna participaci\u00f3n en la vida y sufrimiento del Mes\u00edas que solo ocurre en la comuni\u00f3n de Su salvaci\u00f3n\u201d.2      <\/p>\n<p>Seguir a Jes\u00fas no es una cuesti\u00f3n emocional o moment\u00e1nea. Seguir a Jes\u00fas es un compromiso de por vida en el cual tomamos la decisi\u00f3n de entregarle todo a \u00c9l. <\/p>\n<p>El siguiente t\u00e9rmino que vamos a examinar es el verbo \u201c<b>ver<\/b>\u201d. Juan 1:38 dice que cuando Jes\u00fas se dio cuenta de que los dos disc\u00edpulos lo segu\u00edan, volvi\u00e9ndose los mir\u00f3. Este verbo (<i>the\u00e1omai<\/i>) \u201cdescribe una visi\u00f3n asombrada o atenta, mirar, contemplar\u201d. Destaca el hecho de que Jes\u00fas se detuvo para prestarle atenci\u00f3n a estos dos hombres que lo segu\u00edan. [El diccionario Merriam- Webster] lo define como \u201cfijar la mirada de forma intensa, a menudo con entusiasmo o atenci\u00f3n directa\u201d.4 Jes\u00fas se detuvo para estudiar a estos dos hombres.    <span class=\"Apple-converted-space\"> <\/span>Muchas personas no pueden mirar a otra directamente a los ojos, especialmente aquellas que tienen algo que ocultar. La capacidad para mantener el contacto visual dice mucho de su convicci\u00f3n. Aconsejo a las personas a mantener contacto visual con aquellos que est\u00e1n en autoridad. Esa mirada directa es indicativa de que usted no tiene nada que ocultar. As\u00ed es Jes\u00fas; nos mira directamente a los ojos. No olvidemos que los ojos de Jes\u00fas son penetrantes e inquisitivos. No hay nada oculto, encubierto o secreto para \u00c9l. Jes\u00fas nos conoce mejor de lo que nosotros nos conocemos.       <\/p>\n<p>Despu\u00e9s de mirarlos de forma inquisitiva, Jes\u00fas les pregunt\u00f3 a los dos: \u201c<b>\u00bfQu\u00e9 busc\u00e1is?<\/b>\u201d.<\/p>\n<p>[Observe], Jes\u00fas no les pregunt\u00f3: \u201c\u00bfA qui\u00e9n busc\u00e1is?\u201d, sino \u201c\u00bfQu\u00e9 busc\u00e1is?\u201d o \u201c\u00bfQu\u00e9 est\u00e1is buscando?\u201d Esta pregunta tiene que ver con nuestros planes personales \u2013nuestros intereses\u2013 al seguir a Jes\u00fas. Pero a Jes\u00fas le interesa saber si le seguimos por beneficio personal o por amor y obediencia. Le interesa saber si buscamos al dador de cosas buenas o al Cordero de Dios que quita el pecado del mundo. Pedro mismo estaba interesado en saber cu\u00e1l era el beneficio que \u00e9l [y los dem\u00e1s disc\u00edpulos] obtendr\u00eda al seguir a Jes\u00fas. \u201cHe aqu\u00ed, nosotros lo hemos dejado todo, y te hemos seguido; \u00bfqu\u00e9, pues, tendremos?\u201d, dijo Pedro. Respondiendo Jes\u00fas le prometi\u00f3 que se sentar\u00edan sobre doce tronos, para juzgar a las doce tribus de Israel, y recibir\u00edan cien veces m\u00e1s de todo lo que hab\u00edan dejado atr\u00e1s y heredar\u00edan la vida eterna (Mateo 19:27-29). Marcos a\u00f1ade al enunciado cien veces m\u00e1s la frase \u201ccon persecuciones\u201d (Marcos 10:30). A Jes\u00fas le interesa saber por qu\u00e9 le seguimos. En la actualidad, muchos siguen a Jes\u00fas por ganancia personal, posiciones y poder. El discipulado requiere que el disc\u00edpulo renuncie a todo por amor a Jes\u00fas. No tiene nada que ver con <i>qu\u00e9 podemos recibir<\/i>, sino <i>qu\u00e9 podemos dar<\/i>. Jes\u00fas quiere saber cu\u00e1n comprometidos estamos con el discipulado.            <\/p>\n<p>Veamos ahora la forma en que Andr\u00e9s se dirigi\u00f3 a Jes\u00fas y la pregunta que le hizo sobre Su hogar: \u201c<b>Rab\u00ed, \u00bfd\u00f3nde moras<\/b>?\u201d Esta es la primera vez que a Jes\u00fas se le llama \u201cRab\u00ed\u201d en el Evangelio de Juan. Llamar a alguien \u201crab\u00ed\u201d era una se\u00f1al de respeto y obediencia. Esto demostraba el poder y la autoridad de Jes\u00fas como maestro. Hab\u00eda una diferencia entre Jes\u00fas y los rabinos de Su \u00e9poca. Eduard Lohse dice, \u201cLa autoridad con la que Jes\u00fas ense\u00f1\u00f3 significa que la formaci\u00f3n de Sus disc\u00edpulos no estaba orientada a que se convirtieran en rabinos independientes. Ellos seguir\u00edan siendo disc\u00edpulos, y \u00c9l seguir\u00eda siendo su Maestro.      <span class=\"Apple-converted-space\"> <\/span>Se les prohibi\u00f3 expresamente llamarse rabinos (Mateo 23:8)\u201d. En otras palabras, el discipulado no es cuesti\u00f3n de unos pocos a\u00f1os de estudio y graduarse, sino una relaci\u00f3n para toda la vida. No importa el tiempo que tengamos, seguimos siendo disc\u00edpulos, y Jes\u00fas sigue siendo nuestro Maestro.<\/p>\n<p>La pregunta \u201c<b>\u00bfD\u00f3nde moras?<\/b>\u201d es importante porque denota un inter\u00e9s en seguir a Jes\u00fas. El verbo \u201cmorar\u201d (<i>meneis<\/i>) significa, entre otras cosas, \u201cpermanecer en un lugar\u201d, \u201cesperar\u201d, \u201cestar en la casa\u201d, \u201cpasar la noche\u201d. La pregunta de los disc\u00edpulos infiere que ten\u00edan la intenci\u00f3n de quedarse con el Se\u00f1or. Esto significa que el discipulado requiere un compromiso de permanecer con Jes\u00fas; es <b>permanecer<\/b> con \u00c9l y seguirle, tal como lo dijo en la ense\u00f1anza sobre la vid verdadera en Juan 15. Este [pasaje] subraya la importancia de permanecer en \u00c9l. En los vers\u00edculos 4 al 10, Jes\u00fas repite el verbo \u201cpermanece\u201d en sus distintas variaciones diez veces. As\u00ed que, el discipulado transformador es posible cuando permanecemos, nos movemos y nos quedamos con Jes\u00fas.     <\/p>\n<p>Jes\u00fas les respondi\u00f3 a los disc\u00edpulos, diciendo, \u201c<b>venid y ved<\/b>\u201d. Puesto que ellos hab\u00edan tomado la decisi\u00f3n de quedarse con Jes\u00fas, entonces \u00c9l les mostr\u00f3 d\u00f3nde moraba. La invitaci\u00f3n \u201cvenid y ved\u201d se repite varias veces a lo largo del Evangelio de Juan. Esta es una invitaci\u00f3n a seguir, conocer y comprometerse con el discipulado de Jes\u00fas. Juan dice: \u201cFueron, y vieron donde moraba, y se quedaron con \u00e9l aquel d\u00eda; porque era como la hora d\u00e9cima. (1:39). El verbo <i>meneis<\/i> (morar) que Andr\u00e9s utiliz\u00f3 para preguntarle a Jes\u00fas d\u00f3nde se quedar\u00eda es el mismo que se utiliza para enfatizar que los disc\u00edpulos \u201cse quedaron\u201d con Jes\u00fas. [El texto] hace hincapi\u00e9 en la importancia de \u201cpermanecer\u201d para que ocurra un discipulado transformador. Para aquellos dos disc\u00edpulos, la decisi\u00f3n estaba tomada y no hab\u00eda vuelta atr\u00e1s. Ese es el verdadero discipulado. Nos movemos con Jes\u00fas y permanecemos con \u00c9l.        <\/p>\n<p>Como podemos ver, Jes\u00fas conoce a todos a quienes llama; por Su escrutinio pas\u00f3 Andr\u00e9s y el otro disc\u00edpulo. Asimismo, cuando Andr\u00e9s le llev\u00f3 a su hermano Pedro, \u00c9l tambi\u00e9n lo mir\u00f3 (<i>emblepo<\/i>) y lo llam\u00f3 Cefas, que en arameo significa roca o piedra (equivalente a Pedro en griego). Es decir, Jes\u00fas vio a Pedro tal como era, pero tambi\u00e9n vio en \u00e9l el potencial que ten\u00eda como resultado de vivir una vida de continuo discipulado con Jes\u00fas.   <\/p>\n<p>Juan contin\u00faa diciendo que Jes\u00fas hall\u00f3 a Felipe, lo llam\u00f3 y le dijo: \u201cS\u00edgueme\u201d (1:43). Tal vez haya escuchado hablar sobre la palabra \u201c<i>eureka<\/i>\u201d, que hace referencia al descubrimiento que hizo [el matem\u00e1tico griego] Arqu\u00edmedes sobre el principio de flotaci\u00f3n en la ba\u00f1era. El t\u00e9rmino <i>eureka<\/i> significa \u201clo he encontrado despu\u00e9s de buscar\u201d.  <span class=\"Apple-converted-space\"> <\/span>Esto nos da a entender que Jes\u00fas intencionadamente busc\u00f3 y encontr\u00f3 a Felipe. Felipe, a su vez, busc\u00f3 a Natanael, quien dudaba de que algo bueno saliera de Nazaret. Felipe repiti\u00f3 a Natanael lo mismo que Jes\u00fas le dijo a Andr\u00e9s: \u201cVen y ve\u201d (v. 46).<span class=\"Apple-converted-space\"> <\/span><\/p>\n<p>Cuando Jes\u00fas vio que Natanael se le acercaba, dijo: \u201che aqu\u00ed un verdadero israelita, en quien no hay enga\u00f1o\u201d (v. 47). Natanael se sorprendi\u00f3 al escuchar dicha afirmaci\u00f3n, y le pregunt\u00f3 a Jes\u00fas de d\u00f3nde lo conoc\u00eda. Seguramente la respuesta de Jes\u00fas lo dej\u00f3 at\u00f3nito: \u201cAntes que Felipe te llamara, cuando estabas debajo de la higuera, te vi\u201d (v. 48). El verbo <i>eidon<\/i>, traducido aqu\u00ed como \u201cver\u201d, est\u00e1 conectado con el verbo \u201cconocer\u201d. Jes\u00fas le dio a entender a Natanael que ya lo conoc\u00eda. Jes\u00fas conoc\u00eda su integridad, su car\u00e1cter y su honestidad, a diferencia de su antepasado Jacob, quien era un enga\u00f1ador, Jes\u00fas dijo que \u201cno hab\u00eda enga\u00f1o en \u00e9l\u201d. Esta afirmaci\u00f3n impuls\u00f3 a Natanael a hacer una de las confesiones cristol\u00f3gicas m\u00e1s completas sobre Jes\u00fas. Primero, lo llam\u00f3 Rab\u00ed, reconociendo Su autoridad como maestro. Luego dijo: \u201cT\u00fa eres el Hijo de Dios\u201d, reconociendo Su relaci\u00f3n con Dios y Su deidad. Acto seguido, dijo: \u201cT\u00fa eres el Rey de Israel\u201d, reconoci\u00e9ndolo como la ra\u00edz del \u00e1rbol de Isa\u00ed, el heredero del trono de Israel.          <span class=\"Apple-converted-space\"> <\/span><\/p>\n<p>[La Escritura] muestra otros casos en los que Jes\u00fas revela Su conocimiento de las personas. Juan 2:23- 25 dice que despu\u00e9s de la fiesta de la pascua en Jerusal\u00e9n, \u201c\u2026muchos creyeron en su nombre, viendo las se\u00f1ales que hac\u00eda. Pero Jes\u00fas mismo no se fiaba de ellos, porque conoc\u00eda a todos, y no ten\u00eda necesidad de que nadie le diese testimonio\u2026 pues \u00e9l sab\u00eda lo que hab\u00eda en el hombre\u201d. Al final del cap\u00edtulo 6, tras el gran \u00e9xodo de disc\u00edpulos, Jes\u00fas le pregunt\u00f3 a los Doce si ellos tambi\u00e9n quer\u00edan marcharse. Juan escribe:   <span class=\"Apple-converted-space\"> <\/span><\/p>\n<p>Simon Peter answered him, \u201cLord, to whom shall we go? You have the words of eternal life. We have come to believe and to know that you are the Holy One of God.\u201d Then Jesus replied, \u201cHave I not chosen you, the Twelve? Yet one of you is a devil!\u201d (He meant Judas, the son of Simon Iscariot, though one of the Twelve, was later going to betray him). (John 6:68\u201370 NIV)  <span class=\"Apple-converted-space\"> <\/span><\/p>\n<p>As\u00ed que no hay duda de que Jes\u00fas nos conoce \u00edntimamente. Nos conoce por nombre, pero m\u00e1s importante, conoce nuestros corazones. No hay nada que podamos ocultarle; conoce si somos enga\u00f1adores o no. Conoce si tenemos un Judas dentro de nosotros, dispuesto a venderlo y traicionarlo por dinero. Para ser transformados a la semejanza de Jes\u00fas, tenemos que estar dispuestos a pasar la prueba ante Sus ojos. Siempre me pregunto qu\u00e9 ve Jes\u00fas en m\u00ed cuando Sus ojos me examinan. \u00a1H\u00e1gase la misma pregunta!       <span class=\"Apple-converted-space\"> <\/span><\/p>\n<p>_________________<\/p>\n<p>[1] Gerhard Kittel, \u201c\u1f08\u03ba\u03bf\u03bb\u03bf\u03c5\u03b8\u03ad\u03c9, \u1f18\u03be-, \u1f18\u03c0-, \u03a0\u03b1\u03c1-, \u03a3\u03c5\u03bd\u03b1\u03ba\u03bf\u03bb\u03bf\u03c5\u03b8\u03ad\u03c9,\u201d in <i>Theological Dictionary of the New Testament<\/i>, ed. Gerhard Kittel, Geoffrey W. Bromiley, y Gerhard Friedrich (Grand Rapids, MI: Eerdmans, 1964), 213\u2013215. <span class=\"Apple-converted-space\"> <\/span><\/p>\n<p>[2] Kittel, \u201c\u1f08\u03ba\u03bf\u03bb\u03bf\u03c5\u03b8\u03ad\u03c9, \u1f18\u03be-, \u1f18\u03c0-, \u03a0\u03b1\u03c1-, \u03a3\u03c5\u03bd\u03b1\u03ba\u03bf\u03bb\u03bf\u03c5\u03b8\u03ad\u03c9,\u201d en <i>Theological Dictionary of the New Testament<\/i>, 213\u2013215.<span class=\"Apple-converted-space\"> <\/span><\/p>\n<p>[3] Wilhelm Michaelis, \u201c\u1f49\u03c1\u03ac\u03c9, \u0395\u1f36\u03b4\u03bf\u03bd, \u0392\u03bb\u03ad\u03c0\u03c9, \u1f48\u03c0\u03c4\u03ac\u03bd\u03bf\u03bc\u03b1\u03b9, \u0398\u03b5\u03ac\u03bf\u03bc\u03b1\u03b9, \u0398\u03b5\u03c9\u03c1\u03ad\u03c9, \u1f08\u03cc\u03c1\u03b1\u03c4\u03bf\u03c2, \u1f49\u03c1\u03b1\u03c4\u03cc\u03c2, \u1f4d\u03c1\u03b1\u03c3\u03b9\u03c2, \u1f4d\u03c1\u03b1\u03bc\u03b1, \u1f48\u03c0\u03c4\u03b1\u03c3\u03af\u03b1, \u0391\u1f50\u03c4\u03cc\u03c0\u03c4\u03b7\u03c2, \u1f18\u03c0\u03cc\u03c0\u03c4\u03b7\u03c2, \u1f18\u03c0\u03bf\u03c0\u03c4\u03b5\u03cd\u03c9, \u1f48\u03c6\u03b8\u03b1\u03bb\u03bc\u03cc\u03c2,\u201d en <i>Theological Dictionary of the New Testament<\/i>, 345.<span class=\"Apple-converted-space\"> <\/span><\/p>\n<p>[4] Merriam-Webster Dictionary, s.v. \u201cgaze,\u201d https:\/\/www.merriam-webster.com\/dictionary\/gaze.<span class=\"Apple-converted-space\"> <\/span><\/p>\n<p>[5] Eduard Lohse, \u201c\u1fec\u03b1\u03b2\u03b2\u03af, \u1fec\u03b1\u03b2\u03b2\u03bf\u03c5\u03bd\u03af,\u201d en <i>Theological Dictionary of the New Testament<\/i>, 964.<span class=\"Apple-converted-space\"> <\/span><\/p>\n<p>[6] Lohse, \u201c\u1fec\u03b1\u03b2\u03b2\u03af, \u1fec\u03b1\u03b2\u03b2\u03bf\u03c5\u03bd\u03af,\u201d en <i>Theological Dictionary of the New Testament<\/i>, 964.<span class=\"Apple-converted-space\"> <\/span><\/p>\n<p>[7] Herbert Preisker, \u201c\u0395\u1f51\u03c1\u03af\u03c3\u03ba\u03c9,\u201d en <i>Theological Dictionary of the New Testament<\/i>, 769.<span class=\"Apple-converted-space\"> <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas conoce a Sus disc\u00edpulos | Parte 2 Nuestro objetivo en esta segunda parte se centrar\u00e1 en enfatizar el conocimiento que tiene Jes\u00fas de aquellos a quienes llama. Pero antes de proseguir, es importante recordar que el discipulado tal y como lo ejemplific\u00f3 Jes\u00fas no es un acontecimiento moment\u00e1neo, sino un compromiso de toda la [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":28734,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[375],"tags":[202],"class_list":["post-28803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-centro-para-liderazgo-biblico","tag-mensajero-ala-blanca"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Discipulado: Un compromiso hacia nuestra transformaci\u00f3n | COGOP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cogop.org\/discipleship-a-commitment-to-our-transformation-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Discipulado: Un compromiso hacia nuestra transformaci\u00f3n | COGOP\" \/>\n<meta property=\"og:description\" content=\"Jes\u00fas conoce a Sus disc\u00edpulos | Parte 2 Nuestro objetivo en esta segunda parte se centrar\u00e1 en enfatizar el conocimiento que tiene Jes\u00fas de aquellos a quienes llama. Pero antes de proseguir, es importante recordar que el discipulado tal y como lo ejemplific\u00f3 Jes\u00fas no es un acontecimiento moment\u00e1neo, sino un compromiso de toda la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cogop.org\/discipleship-a-commitment-to-our-transformation-2\/\" \/>\n<meta property=\"og:site_name\" content=\"COGOP\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cogop\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-23T08:00:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cogop.org\/wp-content\/uploads\/2025\/09\/19_FB_LUMO_Jesus_Disciples_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Charlie Scruggs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cogop\" \/>\n<meta name=\"twitter:site\" content=\"@cogop\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charlie Scruggs\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cogop.org\\\/discipleship-a-commitment-to-our-transformation-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cogop.org\\\/discipleship-a-commitment-to-our-transformation-2\\\/\"},\"author\":{\"name\":\"Charlie Scruggs\",\"@id\":\"https:\\\/\\\/cogop.org\\\/#\\\/schema\\\/person\\\/6bfee56ce98d03b7d7dcd90594c4af6b\"},\"headline\":\"Discipulado: Un compromiso hacia nuestra transformaci\u00f3n\",\"datePublished\":\"2025-09-23T08:00:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cogop.org\\\/discipleship-a-commitment-to-our-transformation-2\\\/\"},\"wordCount\":2210,\"publisher\":{\"@id\":\"https:\\\/\\\/cogop.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cogop.org\\\/discipleship-a-commitment-to-our-transformation-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cogop.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/19_FB_LUMO_Jesus_Disciples_1920.jpg\",\"keywords\":[\"Mensajero Ala Blanca\"],\"articleSection\":[\"Centro para Liderazgo B\u00edblico\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cogop.org\\\/discipleship-a-commitment-to-our-transformation-2\\\/\",\"url\":\"https:\\\/\\\/cogop.org\\\/discipleship-a-commitment-to-our-transformation-2\\\/\",\"name\":\"Discipulado: Un compromiso hacia nuestra transformaci\u00f3n | COGOP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cogop.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cogop.org\\\/discipleship-a-commitment-to-our-transformation-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cogop.org\\\/discipleship-a-commitment-to-our-transformation-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cogop.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/19_FB_LUMO_Jesus_Disciples_1920.jpg\",\"datePublished\":\"2025-09-23T08:00:45+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cogop.org\\\/discipleship-a-commitment-to-our-transformation-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cogop.org\\\/discipleship-a-commitment-to-our-transformation-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cogop.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/19_FB_LUMO_Jesus_Disciples_1920.jpg\",\"contentUrl\":\"https:\\\/\\\/cogop.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/19_FB_LUMO_Jesus_Disciples_1920.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cogop.org\\\/discipleship-a-commitment-to-our-transformation-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cogop.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Discipulado: Un compromiso hacia nuestra transformaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cogop.org\\\/#website\",\"url\":\"https:\\\/\\\/cogop.org\\\/\",\"name\":\"Church of God of Prophecy\",\"description\":\"Reconciling the World to Christ\",\"publisher\":{\"@id\":\"https:\\\/\\\/cogop.org\\\/#organization\"},\"alternateName\":\"COGOP\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cogop.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cogop.org\\\/#organization\",\"name\":\"Church of God of Prophecy\",\"alternateName\":\"COGOP\",\"url\":\"https:\\\/\\\/cogop.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cogop.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cogop.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logo-cogop.webp\",\"contentUrl\":\"https:\\\/\\\/cogop.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logo-cogop.webp\",\"width\":500,\"height\":118,\"caption\":\"Church of God of Prophecy\"},\"image\":{\"@id\":\"https:\\\/\\\/cogop.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cogop\",\"https:\\\/\\\/x.com\\\/cogop\",\"https:\\\/\\\/www.instagram.com\\\/cogoppics\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@COGOPMedia\",\"https:\\\/\\\/open.spotify.com\\\/user\\\/g1d13yyaprw0wrr2woer8edyp?si=a32b364b555f4d4d\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cogop.org\\\/#\\\/schema\\\/person\\\/6bfee56ce98d03b7d7dcd90594c4af6b\",\"name\":\"Charlie Scruggs\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c625851004478f5bd86245a070a2090fcb008cf91bfabf0162fca05d324663b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c625851004478f5bd86245a070a2090fcb008cf91bfabf0162fca05d324663b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c625851004478f5bd86245a070a2090fcb008cf91bfabf0162fca05d324663b?s=96&d=mm&r=g\",\"caption\":\"Charlie Scruggs\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Discipulado: Un compromiso hacia nuestra transformaci\u00f3n | COGOP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cogop.org\/discipleship-a-commitment-to-our-transformation-2\/","og_locale":"es_ES","og_type":"article","og_title":"Discipulado: Un compromiso hacia nuestra transformaci\u00f3n | COGOP","og_description":"Jes\u00fas conoce a Sus disc\u00edpulos | Parte 2 Nuestro objetivo en esta segunda parte se centrar\u00e1 en enfatizar el conocimiento que tiene Jes\u00fas de aquellos a quienes llama. Pero antes de proseguir, es importante recordar que el discipulado tal y como lo ejemplific\u00f3 Jes\u00fas no es un acontecimiento moment\u00e1neo, sino un compromiso de toda la [&hellip;]","og_url":"https:\/\/cogop.org\/discipleship-a-commitment-to-our-transformation-2\/","og_site_name":"COGOP","article_publisher":"https:\/\/www.facebook.com\/cogop","article_published_time":"2025-09-23T08:00:45+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/cogop.org\/wp-content\/uploads\/2025\/09\/19_FB_LUMO_Jesus_Disciples_1920.jpg","type":"image\/jpeg"}],"author":"Charlie Scruggs","twitter_card":"summary_large_image","twitter_creator":"@cogop","twitter_site":"@cogop","twitter_misc":{"Escrito por":"Charlie Scruggs","Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cogop.org\/discipleship-a-commitment-to-our-transformation-2\/#article","isPartOf":{"@id":"https:\/\/cogop.org\/discipleship-a-commitment-to-our-transformation-2\/"},"author":{"name":"Charlie Scruggs","@id":"https:\/\/cogop.org\/#\/schema\/person\/6bfee56ce98d03b7d7dcd90594c4af6b"},"headline":"Discipulado: Un compromiso hacia nuestra transformaci\u00f3n","datePublished":"2025-09-23T08:00:45+00:00","mainEntityOfPage":{"@id":"https:\/\/cogop.org\/discipleship-a-commitment-to-our-transformation-2\/"},"wordCount":2210,"publisher":{"@id":"https:\/\/cogop.org\/#organization"},"image":{"@id":"https:\/\/cogop.org\/discipleship-a-commitment-to-our-transformation-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cogop.org\/wp-content\/uploads\/2025\/09\/19_FB_LUMO_Jesus_Disciples_1920.jpg","keywords":["Mensajero Ala Blanca"],"articleSection":["Centro para Liderazgo B\u00edblico"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cogop.org\/discipleship-a-commitment-to-our-transformation-2\/","url":"https:\/\/cogop.org\/discipleship-a-commitment-to-our-transformation-2\/","name":"Discipulado: Un compromiso hacia nuestra transformaci\u00f3n | COGOP","isPartOf":{"@id":"https:\/\/cogop.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cogop.org\/discipleship-a-commitment-to-our-transformation-2\/#primaryimage"},"image":{"@id":"https:\/\/cogop.org\/discipleship-a-commitment-to-our-transformation-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cogop.org\/wp-content\/uploads\/2025\/09\/19_FB_LUMO_Jesus_Disciples_1920.jpg","datePublished":"2025-09-23T08:00:45+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cogop.org\/discipleship-a-commitment-to-our-transformation-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cogop.org\/discipleship-a-commitment-to-our-transformation-2\/#primaryimage","url":"https:\/\/cogop.org\/wp-content\/uploads\/2025\/09\/19_FB_LUMO_Jesus_Disciples_1920.jpg","contentUrl":"https:\/\/cogop.org\/wp-content\/uploads\/2025\/09\/19_FB_LUMO_Jesus_Disciples_1920.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/cogop.org\/discipleship-a-commitment-to-our-transformation-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cogop.org\/"},{"@type":"ListItem","position":2,"name":"Discipulado: Un compromiso hacia nuestra transformaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/cogop.org\/#website","url":"https:\/\/cogop.org\/","name":"Church of God of Prophecy","description":"Reconciling the World to Christ","publisher":{"@id":"https:\/\/cogop.org\/#organization"},"alternateName":"COGOP","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cogop.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cogop.org\/#organization","name":"Church of God of Prophecy","alternateName":"COGOP","url":"https:\/\/cogop.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cogop.org\/#\/schema\/logo\/image\/","url":"https:\/\/cogop.org\/wp-content\/uploads\/2025\/01\/logo-cogop.webp","contentUrl":"https:\/\/cogop.org\/wp-content\/uploads\/2025\/01\/logo-cogop.webp","width":500,"height":118,"caption":"Church of God of Prophecy"},"image":{"@id":"https:\/\/cogop.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cogop","https:\/\/x.com\/cogop","https:\/\/www.instagram.com\/cogoppics\/","https:\/\/www.youtube.com\/@COGOPMedia","https:\/\/open.spotify.com\/user\/g1d13yyaprw0wrr2woer8edyp?si=a32b364b555f4d4d"]},{"@type":"Person","@id":"https:\/\/cogop.org\/#\/schema\/person\/6bfee56ce98d03b7d7dcd90594c4af6b","name":"Charlie Scruggs","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5c625851004478f5bd86245a070a2090fcb008cf91bfabf0162fca05d324663b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5c625851004478f5bd86245a070a2090fcb008cf91bfabf0162fca05d324663b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c625851004478f5bd86245a070a2090fcb008cf91bfabf0162fca05d324663b?s=96&d=mm&r=g","caption":"Charlie Scruggs"}}]}},"_links":{"self":[{"href":"https:\/\/cogop.org\/es\/wp-json\/wp\/v2\/posts\/28803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cogop.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cogop.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cogop.org\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/cogop.org\/es\/wp-json\/wp\/v2\/comments?post=28803"}],"version-history":[{"count":1,"href":"https:\/\/cogop.org\/es\/wp-json\/wp\/v2\/posts\/28803\/revisions"}],"predecessor-version":[{"id":29138,"href":"https:\/\/cogop.org\/es\/wp-json\/wp\/v2\/posts\/28803\/revisions\/29138"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cogop.org\/es\/wp-json\/wp\/v2\/media\/28734"}],"wp:attachment":[{"href":"https:\/\/cogop.org\/es\/wp-json\/wp\/v2\/media?parent=28803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cogop.org\/es\/wp-json\/wp\/v2\/categories?post=28803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cogop.org\/es\/wp-json\/wp\/v2\/tags?post=28803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}